{"id":3745,"date":"2023-08-25T17:53:22","date_gmt":"2023-08-25T21:53:22","guid":{"rendered":"https:\/\/www.newforma.com\/communicating-and-collaborating-on-model-issues-clashes\/"},"modified":"2023-10-25T12:02:44","modified_gmt":"2023-10-25T16:02:44","slug":"communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles","status":"publish","type":"post","link":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/","title":{"rendered":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":17,"featured_media":6570,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[107],"tags":[133,142,134,144],"class_list":["post-3745","post","type-post","status-publish","format-standard","hentry","category-produit","tag-bim-fr","tag-building-information-modeling-fr","tag-clash-detection-fr","tag-information-management-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les - Newforma<\/title>\n<meta name=\"description\" content=\"La mod\u00e9lisation des donn\u00e9es du b\u00e2timent (BIM) est un \u00e9l\u00e9ment important dans la phase de conception, mais la coordination de la BIM est essentielle tout au long du cycle de vie du projet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/\" \/>\n<meta property=\"og:site_name\" content=\"Newforma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NewformaCo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T21:53:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T16:02:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg\" \/>\n<meta name=\"author\" content=\"Marco D&#039;Amico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@NewformaInc\" \/>\n<meta name=\"twitter:site\" content=\"@NewformaInc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco D&#039;Amico\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/\"},\"author\":{\"name\":\"Marco D'Amico\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#\\\/schema\\\/person\\\/f56ee53090c38fe943488b0de5e3874d\"},\"headline\":\"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les\",\"datePublished\":\"2023-08-25T21:53:22+00:00\",\"dateModified\":\"2023-10-25T16:02:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/\"},\"wordCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/adobestock_831101833-1.jpeg\",\"keywords\":[\"BIM\",\"Building Information Modeling\",\"Clash Detection\",\"Information Management\"],\"articleSection\":[\"Produit\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/\",\"url\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/\",\"name\":\"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les - Newforma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/adobestock_831101833-1.jpeg\",\"datePublished\":\"2023-08-25T21:53:22+00:00\",\"dateModified\":\"2023-10-25T16:02:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/adobestock_831101833-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/adobestock_831101833-1.jpeg\",\"width\":3240,\"height\":2160,\"caption\":\"Construction workers wearing safety gear using technology on a work site with heavy machinery in the background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/\",\"name\":\"Newforma\",\"description\":\"Connect your people to the information they need to deliver excellent projects.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#organization\",\"name\":\"Newforma\",\"url\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-2023_newformalogoicon_4c.png\",\"contentUrl\":\"https:\\\/\\\/www.newforma.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-2023_newformalogoicon_4c.png\",\"width\":512,\"height\":512,\"caption\":\"Newforma\"},\"image\":{\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NewformaCo\\\/\",\"https:\\\/\\\/x.com\\\/NewformaInc\",\"https:\\\/\\\/www.instagram.com\\\/newformainc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@NewformaInc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/newforma-inc\",\"https:\\\/\\\/twitter.com\\\/NewformaInc\"],\"description\":\"Newforma, an Ethos Capital portfolio company, provides Information Management and collaboration software for the Architecture, Engineering, Construction, and Owner\\\/Operator (AECO) industry. We empower AECO firms by delivering technology solutions that drive better project outcomes at every stage of the construction project lifecycle, from design, to ribbon-cutting, and beyond. With over 500,000 users in more than 1,500 firms worldwide, Newforma is trusted by professionals globally to streamline communication, simplify administration, and enable real-time collaboration.\",\"email\":\"support@newforma.com\",\"telephone\":\"+1 (877) 875-8252\",\"legalName\":\"Newforma, Inc.\",\"foundingDate\":\"2004-01-01\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/#\\\/schema\\\/person\\\/f56ee53090c38fe943488b0de5e3874d\",\"name\":\"Marco D'Amico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g\",\"caption\":\"Marco D'Amico\"},\"url\":\"https:\\\/\\\/www.newforma.com\\\/fr\\\/author\\\/mdamico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les - Newforma","description":"La mod\u00e9lisation des donn\u00e9es du b\u00e2timent (BIM) est un \u00e9l\u00e9ment important dans la phase de conception, mais la coordination de la BIM est essentielle tout au long du cycle de vie du projet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/","og_locale":"fr_FR","og_type":"article","og_title":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les","og_url":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/","og_site_name":"Newforma","article_publisher":"https:\/\/www.facebook.com\/NewformaCo\/","article_published_time":"2023-08-25T21:53:22+00:00","article_modified_time":"2023-10-25T16:02:44+00:00","og_image":[{"url":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","type":"","width":"","height":""}],"author":"Marco D'Amico","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","twitter_creator":"@NewformaInc","twitter_site":"@NewformaInc","twitter_misc":{"\u00c9crit par":"Marco D'Amico"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#article","isPartOf":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/"},"author":{"name":"Marco D'Amico","@id":"https:\/\/www.newforma.com\/fr\/#\/schema\/person\/f56ee53090c38fe943488b0de5e3874d"},"headline":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les","datePublished":"2023-08-25T21:53:22+00:00","dateModified":"2023-10-25T16:02:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/"},"wordCount":16,"publisher":{"@id":"https:\/\/www.newforma.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","keywords":["BIM","Building Information Modeling","Clash Detection","Information Management"],"articleSection":["Produit"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/","url":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/","name":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les - Newforma","isPartOf":{"@id":"https:\/\/www.newforma.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#primaryimage"},"image":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","datePublished":"2023-08-25T21:53:22+00:00","dateModified":"2023-10-25T16:02:44+00:00","breadcrumb":{"@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#primaryimage","url":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","contentUrl":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/08\/adobestock_831101833-1.jpeg","width":3240,"height":2160,"caption":"Construction workers wearing safety gear using technology on a work site with heavy machinery in the background."},{"@type":"BreadcrumbList","@id":"https:\/\/www.newforma.com\/fr\/communiquer-et-collaborer-en-cas-de-problemes-et-de-collisions-lies-aux-modeles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.newforma.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Communiquer et collaborer en cas de probl\u00e8mes et de collisions li\u00e9s aux mod\u00e8les"}]},{"@type":"WebSite","@id":"https:\/\/www.newforma.com\/fr\/#website","url":"https:\/\/www.newforma.com\/fr\/","name":"Newforma","description":"Connect your people to the information they need to deliver excellent projects.","publisher":{"@id":"https:\/\/www.newforma.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.newforma.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.newforma.com\/fr\/#organization","name":"Newforma","url":"https:\/\/www.newforma.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.newforma.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/10\/cropped-2023_newformalogoicon_4c.png","contentUrl":"https:\/\/www.newforma.com\/wp-content\/uploads\/2023\/10\/cropped-2023_newformalogoicon_4c.png","width":512,"height":512,"caption":"Newforma"},"image":{"@id":"https:\/\/www.newforma.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NewformaCo\/","https:\/\/x.com\/NewformaInc","https:\/\/www.instagram.com\/newformainc\/","https:\/\/www.youtube.com\/@NewformaInc","https:\/\/www.linkedin.com\/company\/newforma-inc","https:\/\/twitter.com\/NewformaInc"],"description":"Newforma, an Ethos Capital portfolio company, provides Information Management and collaboration software for the Architecture, Engineering, Construction, and Owner\/Operator (AECO) industry. We empower AECO firms by delivering technology solutions that drive better project outcomes at every stage of the construction project lifecycle, from design, to ribbon-cutting, and beyond. With over 500,000 users in more than 1,500 firms worldwide, Newforma is trusted by professionals globally to streamline communication, simplify administration, and enable real-time collaboration.","email":"support@newforma.com","telephone":"+1 (877) 875-8252","legalName":"Newforma, Inc.","foundingDate":"2004-01-01"},{"@type":"Person","@id":"https:\/\/www.newforma.com\/fr\/#\/schema\/person\/f56ee53090c38fe943488b0de5e3874d","name":"Marco D'Amico","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1068f3c41d8155f222340cb3f58ae07e99df2e88d7d28e5c256922a5772d81f2?s=96&d=mm&r=g","caption":"Marco D'Amico"},"url":"https:\/\/www.newforma.com\/fr\/author\/mdamico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/posts\/3745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/comments?post=3745"}],"version-history":[{"count":0,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/posts\/3745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/media\/6570"}],"wp:attachment":[{"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/media?parent=3745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/categories?post=3745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newforma.com\/fr\/wp-json\/wp\/v2\/tags?post=3745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}